{"id":27137,"date":"2023-04-06T15:56:44","date_gmt":"2023-04-06T07:56:44","guid":{"rendered":"https:\/\/www.ajfloor.com\/product\/classic-spc-flooirng-88004\/"},"modified":"2023-06-09T16:55:58","modified_gmt":"2023-06-09T08:55:58","slug":"classic-spc-flooirng-88004","status":"publish","type":"product","link":"https:\/\/www.ajfloor.com\/es\/producto\/classic-spc-flooirng-88004\/","title":{"rendered":"CLASSIC SPC FLOOIRNG 88004"},"content":{"rendered":"<p>Informaci\u00f3n b\u00e1sica sobre productos<\/p>\n<table border=\"1\">\n<tbody>\n<tr>\n<td>Nombre<\/td>\n<td colspan=\"2\">AJ FLOOR Suelo vin\u00edlico superior<\/td>\n<\/tr>\n<tr>\n<td>Grosor del tablero<\/td>\n<td colspan=\"2\">4.0mm,5.0mm 5.5mm, o personalizado<\/td>\n<\/tr>\n<tr>\n<td>Espesor de la capa de desgaste<\/td>\n<td colspan=\"2\">0,3 mm, 0,5 mm 0,7 mm como normal<\/td>\n<\/tr>\n<tr>\n<td>Textura de la superficie<\/td>\n<td colspan=\"2\">Madera, m\u00e1rmol, piedra, cuero, moqueta, etc.<\/td>\n<\/tr>\n<tr>\n<td>Acabado<\/td>\n<td colspan=\"2\">UV (mate, semimate)<\/td>\n<\/tr>\n<tr>\n<td>Instalaci\u00f3n<\/td>\n<td colspan=\"2\">Sistema Click<\/td>\n<\/tr>\n<tr>\n<td>Plazo de entrega<\/td>\n<td colspan=\"2\">1 mes<\/td>\n<\/tr>\n<tr>\n<td>Dimensi\u00f3n<\/td>\n<td>En pulgadas<\/td>\n<td>mm<\/td>\n<\/tr>\n<tr>\n<td>(O personalizado)<\/td>\n<td>7&#8243; * 36&#8243;<\/td>\n<td>180&#215;915<\/td>\n<\/tr>\n<tr>\n<td rowspan=\"3\"> <\/td>\n<td>7&#8243; * 48&#8243;<\/td>\n<td>183&#215;1220<\/td>\n<\/tr>\n<tr>\n<td>9&#8243; * 36&#8243;<\/td>\n<td>228.6X915<\/td>\n<\/tr>\n<tr>\n<td>9&#8243; * 48&#8243;<\/td>\n<td>228.6X1220<\/td>\n<\/tr>\n<tr>\n<td> <\/td>\n<td>12&#8243; * 24&#8243;<\/td>\n<td>305X610<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-18168\" src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/03\/601cfa4962c19-300x204.jpg\" alt=\"Tama\u00f1o del suelo SPC\" width=\"443\" height=\"301\" srcset=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/03\/601cfa4962c19-300x204.jpg 300w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/03\/601cfa4962c19.jpg 600w\" sizes=\"(max-width: 443px) 100vw, 443px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-18167\" src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/03\/601cfa5769005-300x204.jpg\" alt=\"spc vinyl tile size\" width=\"445\" height=\"302\" srcset=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/03\/601cfa5769005-300x204.jpg 300w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/03\/601cfa5769005.jpg 600w\" sizes=\"(max-width: 445px) 100vw, 445px\" \/><\/p>\n\n<figure class=\"is-layout-flex wp-block-gallery-1 wp-block-gallery has-nested-images columns-default is-cropped\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"18403\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/88004-001&#x94FA;&#x88C5;.jpg\" alt=\"\" class=\"wp-image-18403\"\/><figcaption class=\"wp-element-caption\">88004-001<\/figcaption><\/figure>\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"18404\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/88004-002&#x94FA;&#x88C5;.jpg\" alt=\"\" class=\"wp-image-18404\"\/><figcaption class=\"wp-element-caption\">88004-002<\/figcaption><\/figure>\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"18405\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/88004-003&#x94FA;&#x88C5;.jpg\" alt=\"\" class=\"wp-image-18405\"\/><figcaption class=\"wp-element-caption\">88004-003<\/figcaption><\/figure>\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"18406\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/88004-004&#x94FA;&#x88C5;.jpg\" alt=\"\" class=\"wp-image-18406\"\/><figcaption class=\"wp-element-caption\">88004-004<\/figcaption><\/figure>\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"18407\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/88004-005&#x94FA;&#x88C5;.jpg\" alt=\"\" class=\"wp-image-18407\"\/><figcaption class=\"wp-element-caption\">88004-005<\/figcaption><\/figure>\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"18408\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/88004-006&#x94FA;&#x88C5;.jpg\" alt=\"\" class=\"wp-image-18408\"\/><figcaption class=\"wp-element-caption\">88004-006<\/figcaption><\/figure>\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"18409\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/88004-007&#x94FA;&#x88C5;.jpg\" alt=\"\" class=\"wp-image-18409\"\/><figcaption class=\"wp-element-caption\">88004-007<\/figcaption><\/figure>\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"18410\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/88004-008&#x94FA;&#x88C5;.jpg\" alt=\"\" class=\"wp-image-18410\"\/><figcaption class=\"wp-element-caption\">88004-008<\/figcaption><\/figure><\/figure>\n","protected":false},"excerpt":{"rendered":"<table class=\"spec-table\">\n<tbody>\n<tr>\n<td> <\/td>\n<td> <\/td>\n<\/tr>\n<tr>\n<td>Material principal<\/td>\n<td>100% material virgen<\/td>\n<\/tr>\n<tr>\n<td>TallaPersonalizada<\/td>\n<td>continuaci\u00f3n<\/td>\n<\/tr>\n<tr>\n<td>espesor<\/td>\n<td>3,5-8 mm<\/td>\n<\/tr>\n<tr>\n<td>capa de desgaste<\/td>\n<td>0,3mm,0,5mm<\/td>\n<\/tr>\n<tr>\n<td>Color<\/td>\n<td>Cualquier Pantone disponible<\/td>\n<\/tr>\n<tr>\n<td>capa inferior<\/td>\n<td>1mm,1.5mm,2mmEVA\/IXPE<\/td>\n<\/tr>\n<tr>\n<td>MOQ<\/td>\n<td>2000 m2<\/td>\n<\/tr>\n<tr>\n<td>Plazo de entrega<\/td>\n<td>25-30 d\u00edas<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"featured_media":21537,"comment_status":"open","ping_status":"closed","template":"page-templates\/canvas-scroll.php","meta":{"_gspb_post_css":""},"product_cat":[168],"product_tag":[187],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ajfloor.com\/es\/wp-json\/wp\/v2\/product\/27137"}],"collection":[{"href":"https:\/\/www.ajfloor.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ajfloor.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ajfloor.com\/es\/wp-json\/wp\/v2\/comments?post=27137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ajfloor.com\/es\/wp-json\/wp\/v2\/media\/21537"}],"wp:attachment":[{"href":"https:\/\/www.ajfloor.com\/es\/wp-json\/wp\/v2\/media?parent=27137"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ajfloor.com\/es\/wp-json\/wp\/v2\/product_cat?post=27137"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ajfloor.com\/es\/wp-json\/wp\/v2\/product_tag?post=27137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}