{"id":27252,"date":"2023-04-19T09:39:14","date_gmt":"2023-04-19T01:39:14","guid":{"rendered":"https:\/\/www.ajfloor.com\/product\/herringbone-spc-flooring-aj86015\/"},"modified":"2023-04-19T09:39:14","modified_gmt":"2023-04-19T01:39:14","slug":"herringbone-spc-flooring-aj86015","status":"publish","type":"product","link":"https:\/\/www.ajfloor.com\/zh-hant\/product\/herringbone-spc-flooring-aj86015\/","title":{"rendered":"HERRINGBONE SPC FLOORING AJ86015"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Products Basic Information<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Name<\/td><td><a href=\"https:\/\/www.ajfloor.com\/zh-hant\/\" title=\"Home\">AJ FLOOR<\/a> <a href=\"https:\/\/www.ajfloor.com\/zh-hant\/%e4%ba%ba%e5%ad%97%e5%bd%a2spc%e5%9c%b0%e6%9d%bf\/\" title=\"HERRINGBONE SPC FLOORING\">HERRINGBONE SPC FLOORING<\/a><\/td><\/tr><tr><td>Board thickness<\/td><td>4.0mm,5.0mm 5.5mm, or customized<\/td><\/tr><tr><td>Wear layer thickness<\/td><td>0.3mm, 0.5mm 0.7mm as regular<\/td><\/tr><tr><td>Surface Texture<\/td><td>Wood, marble, stone, leather, carpet etc<\/td><\/tr><tr><td>Finish<\/td><td>UV (Matt, Semi-Matt)<\/td><\/tr><tr><td>Installation<\/td><td><a href=\"https:\/\/valinge.se\/flooring-technologies\/floor-locking-technologies\/\" title=\"\">Valinge<\/a> or <a href=\"https:\/\/www.unilintechnologies.com\/en\/technologies\/flooring\/uniclic\" title=\"\">Unilin<\/a> Click System<\/td><\/tr><tr><td>Lead time<\/td><td>1 Month<\/td><\/tr><tr><td>Dimension<\/td><td>Inch\/mm<\/td><\/tr><tr><td>Customized size<\/td><td><strong>129*645MM<\/strong><\/td><\/tr><tr><td>&nbsp;Normal size<\/td><td>7&#8243; * 48&#8243;  (183x1220mm)<\/td><\/tr><tr><td><\/td><td>9&#8243; * 36&#8243;  (228\/230X915mm)<\/td><\/tr><tr><td><\/td><td>9&#8243; * 48&#8243;  (228\/230X1220mm)<\/td><\/tr><tr><td>&nbsp;<\/td><td>12&#8243; * 24&#8243;  (305X610mm)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n<style scoped>#gspb_row-id-gsbp-f2980f17-df07.gspb_row{justify-content:space-between;margin-top:0px;margin-bottom:0px;position:relative;display:flex;flex-wrap:wrap;}#gspb_row-id-gsbp-f2980f17-df07.gspb_row >.gspb_row__content{display:flex;justify-content:space-between;margin:0 auto;width:100%;flex-wrap:wrap;}#gspb_row-id-gsbp-f2980f17-df07.gspb_row div[class^=gspb_row__col]{flex-direction:column;position:relative;}#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--24,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--12,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--11,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--10,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--9,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--8,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--7,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--6,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--5,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--4,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--3,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--2,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--1{padding:15px min(3vw,20px);box-sizing:border-box;}body.gspb-bodyfront #gspb_row-id-gsbp-f2980f17-df07.gspb_row >.gspb_row__content{width:var(--container-width,1200px);}body.gspb-bodyfront #gspb_row-id-gsbp-f2980f17-df07.gspb_row >.gspb_row__content{max-width:var(--normal-container-max-width,1200px);}<\/style>\n<div id=\"gspb_row-id-gsbp-f2980f17-df07\" class=\"gspb_row gspb_row-id-gsbp-f2980f17-df07 wp-block-greenshift-blocks-row alignfull gspb_row-id-gsbp-f2980f17-df07\"><div class=\"gspb_row__content\"> <style scoped>#gspb_col-id-gsbp-7742bd0b-7d0e.gspb_row__col--6{width:50%;}@media (max-width:575.98px){#gspb_col-id-gsbp-7742bd0b-7d0e.gspb_row__col--6{width:100%;}}<\/style>\n<div id=\"gspb_col-id-gsbp-7742bd0b-7d0e\" class=\"gspb_row__col--6 wp-block-greenshift-blocks-row-column  gspb_col-id-gsbp-7742bd0b-7d0e\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"408\" src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/03\/601cfa4962c19.jpg\" alt=\"SPC flooring size\" class=\"wp-image-18168\" srcset=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/03\/601cfa4962c19.jpg 600w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/03\/601cfa4962c19-300x204.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n<style scoped>#gspb_col-id-gsbp-0c9c42a4-1855.gspb_row__col--6{width:50%;}@media (max-width:575.98px){#gspb_col-id-gsbp-0c9c42a4-1855.gspb_row__col--6{width:100%;}}<\/style>\n<div id=\"gspb_col-id-gsbp-0c9c42a4-1855\" class=\"gspb_row__col--6 wp-block-greenshift-blocks-row-column  gspb_col-id-gsbp-0c9c42a4-1855\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" loading=\"lazy\" width=\"600\" height=\"408\" src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/03\/601cfa5769005.jpg\" alt=\"spc vinyl tile size\" class=\"wp-image-18167\" srcset=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/03\/601cfa5769005.jpg 600w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/03\/601cfa5769005-300x204.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n <\/div><\/div>\n\n\n\n<figure class=\"is-layout-flex wp-block-gallery-1 wp-block-gallery has-nested-images columns-1 is-cropped\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"800\" data-id=\"19185\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-6.jpg\" alt=\"\" class=\"wp-image-19185\" srcset=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-6.jpg 800w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-6-300x300.jpg 300w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-6-150x150.jpg 150w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-6-768x768.jpg 768w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-6-600x600.jpg 600w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-6-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"800\" data-id=\"19184\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-5.jpg\" alt=\"\" class=\"wp-image-19184\" srcset=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-5.jpg 800w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-5-300x300.jpg 300w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-5-150x150.jpg 150w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-5-768x768.jpg 768w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-5-600x600.jpg 600w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-5-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"800\" data-id=\"19183\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-4.jpg\" alt=\"\" class=\"wp-image-19183\" srcset=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-4.jpg 800w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-4-300x300.jpg 300w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-4-150x150.jpg 150w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-4-768x768.jpg 768w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-4-600x600.jpg 600w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-4-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"800\" data-id=\"19182\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-3.jpg\" alt=\"\" class=\"wp-image-19182\" srcset=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-3.jpg 800w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-3-300x300.jpg 300w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-3-150x150.jpg 150w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-3-768x768.jpg 768w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-3-600x600.jpg 600w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-3-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"800\" data-id=\"19181\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-2.jpg\" alt=\"\" class=\"wp-image-19181\" srcset=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-2.jpg 800w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-2-300x300.jpg 300w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-2-150x150.jpg 150w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-2-768x768.jpg 768w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-2-600x600.jpg 600w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-2-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" loading=\"lazy\" width=\"800\" height=\"800\" data-id=\"19180\"  src=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-1.jpg\" alt=\"\" class=\"wp-image-19180\" srcset=\"https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-1.jpg 800w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-1-300x300.jpg 300w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-1-150x150.jpg 150w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-1-768x768.jpg 768w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-1-600x600.jpg 600w, https:\/\/www.ajfloor.com\/wp-content\/uploads\/2023\/04\/86005-1-100x100.jpg 100w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n<\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<table class=\"spec-table\">\n<tbody>\n<tr>\n<td>\u00a0<\/td>\n<td>\u00a0<\/td>\n<\/tr>\n<tr>\n<td>Main Material<\/td>\n<td>100% virgin material<\/td>\n<\/tr>\n<tr>\n<td>SizeCustomed<\/td>\n<td>continued<\/td>\n<\/tr>\n<tr>\n<td>thickness<\/td>\n<td>3.5-8mm<\/td>\n<\/tr>\n<tr>\n<td>wearlayer<\/td>\n<td>0.3mm,0.5mm<\/td>\n<\/tr>\n<tr>\n<td>Color<\/td>\n<td>Any Pantone Available<\/td>\n<\/tr>\n<tr>\n<td>underlayer<\/td>\n<td>1mm,1.5mm,2mmEVA\/IXPE<\/td>\n<\/tr>\n<tr>\n<td>MOQ<\/td>\n<td>2000 m2<\/td>\n<\/tr>\n<tr>\n<td>Lead Time<\/td>\n<td>25-30 days<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"featured_media":25649,"comment_status":"closed","ping_status":"closed","template":"page-templates\/canvas-scroll.php","meta":{"_gspb_post_css":"#gspb_col-id-gsbp-7742bd0b-7d0e.gspb_row__col--6{width:50%}@media (max-width:575.98px){#gspb_col-id-gsbp-7742bd0b-7d0e.gspb_row__col--6{width:100%}}#gspb_col-id-gsbp-0c9c42a4-1855.gspb_row__col--6{width:50%}@media (max-width:575.98px){#gspb_col-id-gsbp-0c9c42a4-1855.gspb_row__col--6{width:100%}}#gspb_row-id-gsbp-f2980f17-df07.gspb_row{justify-content:space-between;margin-top:0;margin-bottom:0;position:relative;display:flex;flex-wrap:wrap}#gspb_row-id-gsbp-f2980f17-df07.gspb_row>.gspb_row__content{display:flex;justify-content:space-between;margin:0 auto;width:100%;flex-wrap:wrap}#gspb_row-id-gsbp-f2980f17-df07.gspb_row div[class^=gspb_row__col]{flex-direction:column;position:relative}#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--1,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--10,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--11,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--12,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--2,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--24,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--3,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--4,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--5,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--6,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--7,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--8,#gspb_row-id-gsbp-f2980f17-df07.gspb_row .gspb_row__col--9{padding:15px min(3vw,20px);box-sizing:border-box}body.gspb-bodyfront #gspb_row-id-gsbp-f2980f17-df07.gspb_row>.gspb_row__content{width:var(--container-width, 1200px);max-width:var(--normal-container-max-width, 1200px)}"},"product_cat":[127],"product_tag":[144],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ajfloor.com\/zh-hant\/wp-json\/wp\/v2\/product\/27252"}],"collection":[{"href":"https:\/\/www.ajfloor.com\/zh-hant\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ajfloor.com\/zh-hant\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ajfloor.com\/zh-hant\/wp-json\/wp\/v2\/comments?post=27252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ajfloor.com\/zh-hant\/wp-json\/wp\/v2\/media\/25649"}],"wp:attachment":[{"href":"https:\/\/www.ajfloor.com\/zh-hant\/wp-json\/wp\/v2\/media?parent=27252"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ajfloor.com\/zh-hant\/wp-json\/wp\/v2\/product_cat?post=27252"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ajfloor.com\/zh-hant\/wp-json\/wp\/v2\/product_tag?post=27252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}